{"id":5393,"date":"2014-12-12T21:58:00","date_gmt":"2014-12-12T19:58:00","guid":{"rendered":"http:\/\/www.bastelesel.de\/?p=5393"},"modified":"2014-12-12T21:58:00","modified_gmt":"2014-12-12T19:58:00","slug":"girlie-weihnachtstisch","status":"publish","type":"post","link":"http:\/\/www.bastelesel.de\/fr\/girlie-weihnachtstisch\/","title":{"rendered":"No\u00ebl girly"},"content":{"rendered":"<p><a href=\"http:\/\/www.bastelesel.de\/girlie-weihnachtstisch\/pinkchristmas1\/\" rel=\"attachment wp-att-5394\"><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-5394 alignleft\" alt=\"Pinkchristmas1\" src=\"http:\/\/www.bastelesel.de\/wp-content\/uploads\/2014\/12\/Pinkchristmas1-400x300.jpg\" height=\"240\" width=\"320\" srcset=\"http:\/\/www.bastelesel.de\/wp-content\/uploads\/2014\/12\/Pinkchristmas1-400x300.jpg 400w, http:\/\/www.bastelesel.de\/wp-content\/uploads\/2014\/12\/Pinkchristmas1.jpg 800w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/a>Le rouge et vert n&rsquo;est pas obligatoire pour les jours de F\u00eates. Juste pour No\u00ebl nous devrions d\u00e9corer notre maison ou la table dans nos couleurs pr\u00e9fer\u00e9es. C&rsquo;est pourquoi je propose une table en rose fuchsia. Point de d\u00e9part fut un paquet de serviettes en papier qui est compl\u00e9t\u00e9 d&rsquo;une petite guirlande, un verre pour bougie chauffe-plat scintillant et la fleur d&rsquo;une rose de No\u00ebl. Des boules de No\u00ebl et des c\u00f4nes de sapin en rose fuchsia et lilas sont nou\u00e9s \u00e0 un ruban-cadeau en rose fuchsia. Un ruban fris\u00e9 est entortill\u00e9 autour de la guirlande et de petites \u00e9toiles en bois (\u00e9galement rose fuchsia, lilas) sont coll\u00e9 dans les interstices. Pour les jours de F\u00eates posez la guirlande sur de petites branches de sapin. La fleur de la rose de No\u00ebl est mise dans une des \u00e9toiles propos\u00e9es par moi le 21. Novembre. Elle est painte en rose fuchsia et accentu\u00e9e par des traces de poudre \u00e9tincelant. Nouez un morceau du ruban de la guirlande autour de l&rsquo;\u00e9prouvette et enfilez-la dans le trou de l&rsquo;\u00e9toile. Dispersez des \u00e9toiles en bois sur la table et si vous voulez collez quelques uns sur un ruban qui vous servira de rond de serviette ensuite.<\/p>\n<p><section id=\"emgoptions\" class=\"easymedia_left emgclearfix isofilcont-vqhlmt\"><ul id=\"filters\" class=\"portfolio-tabs emgoption-set emgclearfix\" data-option-key=\"filter\"><li data-option-value=\"*\"  class=\"emg-default-blue selected\" id=\"emgshowall\">Show All<\/li><li data-option-value=\".fltr5398\" class=\"emg-default-blue \">Girlie-Weihnachtstisch\/Girlie&rsquo;s Holiday\/No\u00ebl girly<\/li><\/ul><\/section><div id=\"isloaderfor-vqhlmt\" class=\"emgajxloader\"><\/div><div style=\"display: none;\" class=\"pagwrap-vqhlmt epgwrp\" id=\"nopagination\"><div class=\"easycontainer-vqhlmt easymedia_center lightboxvqhlmt emgclearfix emgpad\"><div style=\"width:180px; height:180px;\" class=\"easyitem hoverone view da-thumbs preloaderview fltr5398\"><div class=\"iehand\"><a onclick=\"easyActiveStyleSheet('Light');return true;\" class=\"5398-5404 nofoobox\" rel=\"easymedia[showall]\" href=\"http:\/\/www.bastelesel.de\/wp-content\/uploads\/2014\/12\/Pinkchristmas6.jpg\"><img src=\"http:\/\/www.bastelesel.de\/wp-content\/plugins\/easy-media-gallery-pro\/includes\/images\/trans.png\" class=\"emglazy\" data-original=\"http:\/\/www.bastelesel.de\/wp-content\/plugins\/easy-media-gallery-pro\/includes\/class\/timthumb.php?src=http:\/\/www.bastelesel.de\/wp-content\/uploads\/2014\/12\/Pinkchristmas6.jpg&h=180&w=180&zc=0&q=100&a=c\" alt=\"Pinkchristmas6\" title=\"Pinkchristmas6\"\/><article class=\"da-animate da-slideFromRight\"><p class=\"emgfittext\"><\/p><div class=\"forspan\"><span class=\"zoom\"><\/span><\/div><\/article><\/a><\/div><\/div><div style=\"width:180px; height:180px;\" class=\"easyitem hoverone view da-thumbs preloaderview fltr5398\"><div class=\"iehand\"><a onclick=\"easyActiveStyleSheet('Light');return true;\" class=\"5398-5403 nofoobox\" rel=\"easymedia[showall]\" href=\"http:\/\/www.bastelesel.de\/wp-content\/uploads\/2014\/12\/Pinkchristmas5.jpg\"><img src=\"http:\/\/www.bastelesel.de\/wp-content\/plugins\/easy-media-gallery-pro\/includes\/images\/trans.png\" class=\"emglazy\" data-original=\"http:\/\/www.bastelesel.de\/wp-content\/plugins\/easy-media-gallery-pro\/includes\/class\/timthumb.php?src=http:\/\/www.bastelesel.de\/wp-content\/uploads\/2014\/12\/Pinkchristmas5.jpg&h=180&w=180&zc=0&q=100&a=c\" alt=\"Pinkchristmas5\" title=\"Pinkchristmas5\"\/><article class=\"da-animate da-slideFromRight\"><p class=\"emgfittext\"><\/p><div class=\"forspan\"><span class=\"zoom\"><\/span><\/div><\/article><\/a><\/div><\/div><div style=\"width:180px; height:180px;\" class=\"easyitem hoverone view da-thumbs preloaderview fltr5398\"><div class=\"iehand\"><a onclick=\"easyActiveStyleSheet('Light');return true;\" class=\"5398-5402 nofoobox\" rel=\"easymedia[showall]\" href=\"http:\/\/www.bastelesel.de\/wp-content\/uploads\/2014\/12\/Pinkchristmas4.jpg\"><img src=\"http:\/\/www.bastelesel.de\/wp-content\/plugins\/easy-media-gallery-pro\/includes\/images\/trans.png\" class=\"emglazy\" data-original=\"http:\/\/www.bastelesel.de\/wp-content\/plugins\/easy-media-gallery-pro\/includes\/class\/timthumb.php?src=http:\/\/www.bastelesel.de\/wp-content\/uploads\/2014\/12\/Pinkchristmas4.jpg&h=180&w=180&zc=0&q=100&a=c\" alt=\"Pinkchristmas4\" title=\"Pinkchristmas4\"\/><article class=\"da-animate da-slideFromRight\"><p class=\"emgfittext\"><\/p><div class=\"forspan\"><span class=\"zoom\"><\/span><\/div><\/article><\/a><\/div><\/div><div style=\"width:180px; height:180px;\" class=\"easyitem hoverone view da-thumbs preloaderview fltr5398\"><div class=\"iehand\"><a onclick=\"easyActiveStyleSheet('Light');return true;\" class=\"5398-5401 nofoobox\" rel=\"easymedia[showall]\" href=\"http:\/\/www.bastelesel.de\/wp-content\/uploads\/2014\/12\/Pinkchristmas3.jpg\"><img src=\"http:\/\/www.bastelesel.de\/wp-content\/plugins\/easy-media-gallery-pro\/includes\/images\/trans.png\" class=\"emglazy\" data-original=\"http:\/\/www.bastelesel.de\/wp-content\/plugins\/easy-media-gallery-pro\/includes\/class\/timthumb.php?src=http:\/\/www.bastelesel.de\/wp-content\/uploads\/2014\/12\/Pinkchristmas3.jpg&h=180&w=180&zc=0&q=100&a=c\" alt=\"Pinkchristmas3\" title=\"Pinkchristmas3\"\/><article class=\"da-animate da-slideFromRight\"><p class=\"emgfittext\"><\/p><div class=\"forspan\"><span class=\"zoom\"><\/span><\/div><\/article><\/a><\/div><\/div><div style=\"width:180px; height:180px;\" class=\"easyitem hoverone view da-thumbs preloaderview fltr5398\"><div class=\"iehand\"><a onclick=\"easyActiveStyleSheet('Light');return true;\" class=\"5398-5400 nofoobox\" rel=\"easymedia[showall]\" href=\"http:\/\/www.bastelesel.de\/wp-content\/uploads\/2014\/12\/Pinkchristmas2.jpg\"><img src=\"http:\/\/www.bastelesel.de\/wp-content\/plugins\/easy-media-gallery-pro\/includes\/images\/trans.png\" class=\"emglazy\" data-original=\"http:\/\/www.bastelesel.de\/wp-content\/plugins\/easy-media-gallery-pro\/includes\/class\/timthumb.php?src=http:\/\/www.bastelesel.de\/wp-content\/uploads\/2014\/12\/Pinkchristmas2.jpg&h=180&w=180&zc=0&q=100&a=c\" alt=\"Pinkchristmas2\" title=\"Pinkchristmas2\"\/><article class=\"da-animate da-slideFromRight\"><p class=\"emgfittext\"><\/p><div class=\"forspan\"><span class=\"zoom\"><\/span><\/div><\/article><\/a><\/div><\/div>\r\n<div style=\"clear:both;\"><\/div><\/div><\/div><style type=\"text\/css\">\n.pagwrap-vqhlmt .preloaderview {min-width: 90px;min-height: 90px;}\n<\/style>\n<script type=\"text\/javascript\">\njQuery(document).ready(function($) {var $container = $('.easycontainer-vqhlmt');var $win = $(window);$container.emgisotope({itemSelector: '.easyitem',filter: '*',transformsEnabled: true,onLayout: function() {$win.trigger(\"scroll\");}});var $optionSets = $('.isofilcont-vqhlmt .emgoption-set'),$optionLinks = $optionSets.find('li'); \/\/@since 1.5.0.3\n$optionLinks.click(function(){var $this = $(this);if ( $this.hasClass('selected') ) {return false;}\nvar $optionSet = $this.parents('.emgoption-set');$optionSet.find('.selected').removeClass('selected');$this.addClass('selected');var options = {},key = $optionSet.attr('data-option-key'),value = $this.attr('data-option-value');value = value === 'false' ? false : value;options[ key ] = value;if ( key === 'layoutMode') {if ( typeof changeLayoutMode === 'function' ) {changeLayoutMode( $this, options )}} else {$container.emgisotope( options );}\nreturn false;});jQuery(\".pagwrap-vqhlmt .emglazy\").lazy({attribute: \"data-original\",effect: \"fadeIn\",visibleOnly: true,enableThrottle: true,throttle: 250,effectTime: 900,threshold: 100,afterLoad: function(element) {element.after(jQuery(element).readyLoad({ elementId: \"vqhlmt\", isPagination: '', isLazyload: 1, imageCount: \"5\" }));}});jQuery(\".pagwrap-vqhlmt\").fadeIn(1000);jQuery(\"#isloaderfor-vqhlmt\").hide();try {jQuery(\".easycontainer-vqhlmt\").emgisotope( 'reLayout' );} catch(e) {return true;}});<\/script><script type=\"text\/javascript\">\njQuery(document).ready(function() {jQuery( \"#filters li\" ).click(function() {elmntsel = jQuery(this).attr(\"data-option-value\");if (elmntsel == \"*\") {jQuery(\".iehand a\").attr(\"rel\", \"easymedia[showall]\");} else {jQuery(\".\"+elmntsel.substring(1)+\" .iehand a\").attr(\"rel\", \"easymedia[\"+elmntsel+\"]\");}});});<\/script><\/p>","protected":false},"excerpt":{"rendered":"<p>Le rouge et vert n&rsquo;est pas obligatoire pour les jours de F\u00eates. Juste pour No\u00ebl nous devrions d\u00e9corer notre maison ou la table dans nos couleurs pr\u00e9fer\u00e9es. C&rsquo;est pourquoi je propose une table en rose fuchsia. Point de d\u00e9part fut un paquet de serviettes en papier qui est compl\u00e9t\u00e9 d&rsquo;une petite guirlande, un verre pour [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0},"categories":[15],"tags":[],"_links":{"self":[{"href":"http:\/\/www.bastelesel.de\/fr\/wp-json\/wp\/v2\/posts\/5393"}],"collection":[{"href":"http:\/\/www.bastelesel.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.bastelesel.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.bastelesel.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.bastelesel.de\/fr\/wp-json\/wp\/v2\/comments?post=5393"}],"version-history":[{"count":8,"href":"http:\/\/www.bastelesel.de\/fr\/wp-json\/wp\/v2\/posts\/5393\/revisions"}],"predecessor-version":[{"id":5411,"href":"http:\/\/www.bastelesel.de\/fr\/wp-json\/wp\/v2\/posts\/5393\/revisions\/5411"}],"wp:attachment":[{"href":"http:\/\/www.bastelesel.de\/fr\/wp-json\/wp\/v2\/media?parent=5393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.bastelesel.de\/fr\/wp-json\/wp\/v2\/categories?post=5393"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.bastelesel.de\/fr\/wp-json\/wp\/v2\/tags?post=5393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}